{"id":311,"date":"2023-07-10T03:46:14","date_gmt":"2023-07-10T03:46:14","guid":{"rendered":"http:\/\/18.136.196.255\/?page_id=311"},"modified":"2026-03-27T16:18:38","modified_gmt":"2026-03-27T08:18:38","slug":"ourleaders","status":"publish","type":"page","link":"https:\/\/alamflora.com.my\/index.php\/aboutus\/ourleaders\/","title":{"rendered":"Our Leaders"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"311\" class=\"elementor elementor-311\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9d5829 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b9d5829\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ded9b1d\" data-id=\"ded9b1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-546e290 elementor-widget elementor-widget-heading\" data-id=\"546e290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-large\"><u>Our Leaders<\/u><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64114d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"64114d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d03294\" data-id=\"7d03294\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9a324b elementor-widget elementor-widget-heading\" data-id=\"f9a324b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><u>Board of Directors<\/u><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-438caca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"438caca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aaafa12\" data-id=\"aaafa12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b33338b\" data-id=\"b33338b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c3ab64 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3c3ab64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"290\" height=\"386\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-1.png\" class=\"attachment-large size-large wp-image-1166\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-1.png 290w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-1-225x300.png 225w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Tan Sri Abu Kassim Bin Mohamed<\/h3><p class=\"elementor-image-box-description\">Chairman<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9987602\" data-id=\"9987602\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c64c4fa elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c64c4fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0052a6\" data-id=\"f0052a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbd2a3d elementor-widget elementor-widget-spacer\" data-id=\"bbd2a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80f7242 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"80f7242\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-21bf68c\" data-id=\"21bf68c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16762ed elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"16762ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"290\" height=\"386\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-2.png\" class=\"attachment-large size-large wp-image-1167\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-2.png 290w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-2-225x300.png 225w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dato\u2019 Mohamad bin Saif @ Saib<\/h3><p class=\"elementor-image-box-description\">Director<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-32ebe8a\" data-id=\"32ebe8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-411d0d0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"411d0d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"290\" height=\"386\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-6.png\" class=\"attachment-large size-large wp-image-1171\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-6.png 290w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-6-225x300.png 225w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dato\u2019 Sri Mohd Zakaria Bin Ahmad<\/h3><p class=\"elementor-image-box-description\">Director<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-08a2ebd\" data-id=\"08a2ebd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66678ab elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"66678ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"1024\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2026\/03\/new-ceo-syahrunizam-9-766x1024.png\" class=\"attachment-large size-large wp-image-2320\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2026\/03\/new-ceo-syahrunizam-9-766x1024.png 766w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2026\/03\/new-ceo-syahrunizam-9-224x300.png 224w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2026\/03\/new-ceo-syahrunizam-9-768x1027.png 768w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2026\/03\/new-ceo-syahrunizam-9.png 808w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Syahrunizam Samsudin<\/h3><p class=\"elementor-image-box-description\">Director<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7ace82 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b7ace82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cad0330\" data-id=\"cad0330\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed0e0ac elementor-widget elementor-widget-spacer\" data-id=\"ed0e0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-946af06 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"946af06\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cbc0b53\" data-id=\"cbc0b53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a34ef3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5a34ef3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"386\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-7.png\" class=\"attachment-large size-large wp-image-1172\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-7.png 290w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-7-225x300.png 225w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mohd Nazersham Bin  Mansor<\/h3><p class=\"elementor-image-box-description\">Director<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e84cc08\" data-id=\"e84cc08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44a3783 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"44a3783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"386\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-8.png\" class=\"attachment-large size-large wp-image-1173\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-8.png 290w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-8-225x300.png 225w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dr Norida Binti Abdul <br> Rahman<\/h3><p class=\"elementor-image-box-description\">Director<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c8386cc\" data-id=\"c8386cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb14486 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bb14486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"386\" src=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-9.png\" class=\"attachment-large size-large wp-image-1174\" alt=\"\" srcset=\"https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-9.png 290w, https:\/\/alamflora.com.my\/wp-content\/uploads\/2023\/09\/Untitled-9-225x300.png 225w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Datuk Dr. Syed Muhamad<br> bin Syed Abdul Kadir<\/h3><p class=\"elementor-image-box-description\">Director<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our Leaders Board of Directors Tan Sri Abu Kassim Bin Mohamed Chairman Dato\u2019 Mohamad bin Saif @ Saib Director Dato\u2019 Sri Mohd Zakaria Bin Ahmad Director Syahrunizam Samsudin Director Mohd Nazersham Bin Mansor Director Dr Norida Binti Abdul Rahman Director Datuk Dr. Syed Muhamad bin Syed Abdul Kadir Director<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":273,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-311","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/pages\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":75,"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/pages\/311\/revisions"}],"predecessor-version":[{"id":2323,"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/pages\/311\/revisions\/2323"}],"up":[{"embeddable":true,"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/pages\/273"}],"wp:attachment":[{"href":"https:\/\/alamflora.com.my\/index.php\/wp-json\/wp\/v2\/media?parent=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}